{"id":126965268,"date":"2026-02-12T12:00:00","date_gmt":"2026-02-12T12:00:00","guid":{"rendered":"https:\/\/usk.de\/usktitle\/58412"},"modified":"2026-02-12T12:00:00","modified_gmt":"2026-02-12T12:00:00","slug":"58412","status":"publish","type":"usktitle","link":"https:\/\/usk.de\/en\/usktitle\/58412\/","title":{"rendered":"ROMEO IS A DEAD MAN"},"excerpt":{"rendered":"<p>NetEase Games Japan \/ GRASSHOPPER MANUFACTURE INC.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":""},"genre":[771],"language":[650],"platform":[742],"rating":[735],"descriptor":[794,800],"additional_descriptor":[],"class_list":["post-126965268","usktitle","type-usktitle","status-publish","hentry","genre-genremix","language-multilingual","platform-sony-playstation-5","rating-keine-jugendfreigabe-gemaess--14-juschg","descriptor-794","descriptor-800"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usk.de\/en\/usktitle\/58412\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN\" \/>\n<meta property=\"og:description\" content=\"NetEase Games Japan \/ GRASSHOPPER MANUFACTURE INC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usk.de\/en\/usktitle\/58412\/\" \/>\n<meta property=\"og:site_name\" content=\"Unterhaltungssoftware Selbstkontrolle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@usk_de\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/usktitle\\\/58412\\\/\",\"url\":\"https:\\\/\\\/usk.de\\\/en\\\/usktitle\\\/58412\\\/\",\"name\":\"USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#website\"},\"datePublished\":\"2026-02-12T12:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/usktitle\\\/58412\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/usk.de\\\/en\\\/usktitle\\\/58412\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/usktitle\\\/58412\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/usk.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ROMEO IS A DEAD MAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/usk.de\\\/en\\\/\",\"name\":\"Unterhaltungssoftware Selbstkontrolle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usk.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#organization\",\"name\":\"Unterhaltungssoftware Selbstkontrolle (USK)\",\"url\":\"https:\\\/\\\/usk.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/usk.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/USK_Logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/usk.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/USK_Logo@2x.png\",\"width\":520,\"height\":86,\"caption\":\"Unterhaltungssoftware Selbstkontrolle (USK)\"},\"image\":{\"@id\":\"https:\\\/\\\/usk.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/usk_de\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/unterhaltungssoftware-selbstkontrolle-usk\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/USelbstKontrolle\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Unterhaltungssoftware_Selbstkontrolle\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usk.de\/en\/usktitle\/58412\/","og_locale":"en_US","og_type":"article","og_title":"USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN","og_description":"NetEase Games Japan \/ GRASSHOPPER MANUFACTURE INC.","og_url":"https:\/\/usk.de\/en\/usktitle\/58412\/","og_site_name":"Unterhaltungssoftware Selbstkontrolle","twitter_card":"summary_large_image","twitter_site":"@usk_de","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/usk.de\/en\/usktitle\/58412\/","url":"https:\/\/usk.de\/en\/usktitle\/58412\/","name":"USK Altersfreigabe f\u00fcr ROMEO IS A DEAD MAN","isPartOf":{"@id":"https:\/\/usk.de\/en\/#website"},"datePublished":"2026-02-12T12:00:00+00:00","breadcrumb":{"@id":"https:\/\/usk.de\/en\/usktitle\/58412\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/usk.de\/en\/usktitle\/58412\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/usk.de\/en\/usktitle\/58412\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/usk.de\/en\/"},{"@type":"ListItem","position":2,"name":"ROMEO IS A DEAD MAN"}]},{"@type":"WebSite","@id":"https:\/\/usk.de\/en\/#website","url":"https:\/\/usk.de\/en\/","name":"Unterhaltungssoftware Selbstkontrolle","description":"","publisher":{"@id":"https:\/\/usk.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usk.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/usk.de\/en\/#organization","name":"Unterhaltungssoftware Selbstkontrolle (USK)","url":"https:\/\/usk.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/usk.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/usk.de\/wp-content\/uploads\/2019\/02\/USK_Logo@2x.png","contentUrl":"https:\/\/usk.de\/wp-content\/uploads\/2019\/02\/USK_Logo@2x.png","width":520,"height":86,"caption":"Unterhaltungssoftware Selbstkontrolle (USK)"},"image":{"@id":"https:\/\/usk.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/usk_de","https:\/\/de.linkedin.com\/company\/unterhaltungssoftware-selbstkontrolle-usk","https:\/\/www.youtube.com\/user\/USelbstKontrolle","https:\/\/de.wikipedia.org\/wiki\/Unterhaltungssoftware_Selbstkontrolle"]}]}},"_links":{"self":[{"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/usktitle\/126965268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/usktitle"}],"about":[{"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/types\/usktitle"}],"wp:attachment":[{"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/media?parent=126965268"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/genre?post=126965268"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/language?post=126965268"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/platform?post=126965268"},{"taxonomy":"rating","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/rating?post=126965268"},{"taxonomy":"descriptor","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/descriptor?post=126965268"},{"taxonomy":"additional_descriptor","embeddable":true,"href":"https:\/\/usk.de\/en\/wp-json\/wp\/v2\/additional_descriptor?post=126965268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}